{"id":17956,"date":"2025-09-19T15:25:56","date_gmt":"2025-09-19T14:25:56","guid":{"rendered":"https:\/\/www.cnam.ie\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/european-media-freedom-act\/media-ownership-databases\/"},"modified":"2025-11-11T15:47:48","modified_gmt":"2025-11-11T15:47:48","slug":"bunachar-sonrai-uineireacht-na-mean","status":"publish","type":"page","link":"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/an-gniomh-eorpach-um-shaoirse-na-mean\/bunachar-sonrai-uineireacht-na-mean\/","title":{"rendered":"Bunachar sonra\u00ed \u00fain\u00e9ireacht na me\u00e1n"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-1d5875b5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-2f005527\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d9b72e84\"><p class=\"uagb-heading-text\">Is \u00e9 is aidhm d\u2019Airteagal 6 den Ghn\u00edomh Eorpach um Shaoirse na Me\u00e1n (GESM) tr\u00e9dhearcacht in \u00fain\u00e9ireacht na me\u00e1n a r\u00e1th\u00fa agus cuirtear d\u2019oibleag\u00e1id ar na Ballst\u00e1it leis \u00e9 a chur de ch\u00faram ar chomhlachta\u00ed inni\u00fala forbairt a dh\u00e9anamh ar bhunachair sonra\u00ed n\u00e1isi\u00fanta maidir le h\u00fain\u00e9ireacht na me\u00e1n.<\/p><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p>T\u00e1 dh\u00e1 bhunachar sonra\u00ed \u00fain\u00e9ireachta me\u00e1n \u00e1 n-oibri\u00fa againn faoi l\u00e1thair, a forbra\u00edodh i gcomhar le Scoil na Cumars\u00e1ide Ollscoil Chathair Bhaile \u00c1tha Cliath:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"http:\/\/www.mediaownership.ie\/\" target=\"_blank\" rel=\"noopener\">\u00dain\u00e9ireacht na Me\u00e1n, \u00c9ire<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/ireland.mom-gmr.org\/ga\/\" target=\"_blank\" rel=\"noreferrer noopener\">Monat\u00f3ir na h\u00c9ireann ar \u00dain\u00e9ireacht na Me\u00e1n (M\u00daM)<\/a><\/li>\n<\/ul>\n\n\n\n<p>Le <a href=\"https:\/\/www.gov.ie\/ga\/an-roinn-cult%C3%BAir-cumars%C3%A1ide-agus-sp%C3%B3irt\/foilseachain\/general-scheme-for-the-media-regulation-bill\/\" target=\"_blank\" rel=\"noopener\">Sc\u00e9im Ghinear\u00e1lta an Bhille um Rial\u00e1il na Me\u00e1n<\/a> d\u00e9antar for\u00e1il maidir le bunachar sonra\u00ed a bhun\u00fa ar bhonn reacht\u00fail agus raon feidhme leathnaithe agus ceanglais \u00e9igeantacha maidir le f\u00f3gra a thabhairt ann le haghaidh sol\u00e1thraithe seirbh\u00edse me\u00e1n nuair a thugtar faisn\u00e9is \u00e1bhartha cothrom le d\u00e1ta.<\/p>\n\n\n\n<p>Le hAirteagal 6 de GESM agus lena reachta\u00edocht cur chun feidhme, ceangl\u00f3far na bunachair sonra\u00ed at\u00e1 ann cheana a fhorbairt a thuilleadh chun bheith ag teacht le ceanglais GESM. Sainorda\u00edtear leis an Sc\u00e9im Ghinear\u00e1lta go mbeidh faisn\u00e9is a shonra\u00edtear in Airteagal 6(1) de GESM sa bhunachar sonra\u00ed, lena n-\u00e1ir\u00edtear:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ainm \u00fain\u00e9ir\u00ed d\u00edreacha n\u00f3 ind\u00edreacha sol\u00e1thraithe seirbh\u00edse me\u00e1n<\/li>\n\n\n\n<li>Ainmneacha \u00fain\u00e9ir\u00ed tairbhi\u00fala<\/li>\n\n\n\n<li>M\u00e9id bliant\u00fail ioml\u00e1n na f\u00f3gra\u00edochta st\u00e1it a leithdh\u00e1iltear orthu<\/li>\n\n\n\n<li>M\u00e9id ioml\u00e1n an ioncaim f\u00f3gra\u00edochta a fhaightear \u00f3 thr\u00ed\u00fa t\u00edortha<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Nuashonruithe ar bhunachair sonra\u00ed<\/h2>\n\n\n\n<p>Ba cheart f\u00f3gra a thabhairt do <a href=\"mailto:emfa@cnam.ie\">emfa@cnam.ie<\/a> maidir le breiseanna, leasuithe n\u00f3 earr\u00e1id\u00ed sonra\u00ed i mbunachar sonra\u00ed.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Is \u00e9 is aidhm d\u2019Airteagal 6 den Ghn\u00edomh Eorpach um Shaoirse na Me\u00e1n (GESM) tr\u00e9dhearcacht in \u00fain\u00e9ireacht na me\u00e1n a r\u00e1th\u00fa agus cuirtear d\u2019oibleag\u00e1id ar na Ballst\u00e1it leis \u00e9 a chur de ch\u00faram ar chomhlachta\u00ed inni\u00fala forbairt a dh\u00e9anamh ar bhunachair sonra\u00ed n\u00e1isi\u00fanta maidir le h\u00fain\u00e9ireacht na me\u00e1n. T\u00e1 dh\u00e1 bhunachar sonra\u00ed \u00fain\u00e9ireachta me\u00e1n \u00e1 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":17934,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"16335,7618,7630,15122,707,3328","_relevanssi_noindex_reason":"","_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-17956","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bunachar sonra\u00ed \u00fain\u00e9ireacht na me\u00e1n - Coimisi\u00fan na Me\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/an-gniomh-eorpach-um-shaoirse-na-mean\/bunachar-sonrai-uineireacht-na-mean\/\" \/>\n<meta property=\"og:locale\" content=\"ga_IE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bunachar sonra\u00ed \u00fain\u00e9ireacht na me\u00e1n - Coimisi\u00fan na Me\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Is \u00e9 is aidhm d\u2019Airteagal 6 den Ghn\u00edomh Eorpach um Shaoirse na Me\u00e1n (GESM) tr\u00e9dhearcacht in \u00fain\u00e9ireacht na me\u00e1n a r\u00e1th\u00fa agus cuirtear d\u2019oibleag\u00e1id ar na Ballst\u00e1it leis \u00e9 a chur de ch\u00faram ar chomhlachta\u00ed inni\u00fala forbairt a dh\u00e9anamh ar bhunachair sonra\u00ed n\u00e1isi\u00fanta maidir le h\u00fain\u00e9ireacht na me\u00e1n. T\u00e1 dh\u00e1 bhunachar sonra\u00ed \u00fain\u00e9ireachta me\u00e1n \u00e1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/an-gniomh-eorpach-um-shaoirse-na-mean\/bunachar-sonrai-uineireacht-na-mean\/\" \/>\n<meta property=\"og:site_name\" content=\"Coimisi\u00fan na Me\u00e1n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNaM.Ireland\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T15:47:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CNaM_ie\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/tionscal-gairmithe\\\/coid-reachtaiocht\\\/reachtaiocht\\\/an-gniomh-eorpach-um-shaoirse-na-mean\\\/bunachar-sonrai-uineireacht-na-mean\\\/\",\"url\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/tionscal-gairmithe\\\/coid-reachtaiocht\\\/reachtaiocht\\\/an-gniomh-eorpach-um-shaoirse-na-mean\\\/bunachar-sonrai-uineireacht-na-mean\\\/\",\"name\":\"Bunachar sonra\u00ed \u00fain\u00e9ireacht na me\u00e1n - Coimisi\u00fan na Me\u00e1n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/#website\"},\"datePublished\":\"2025-09-19T14:25:56+00:00\",\"dateModified\":\"2025-11-11T15:47:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/tionscal-gairmithe\\\/coid-reachtaiocht\\\/reachtaiocht\\\/an-gniomh-eorpach-um-shaoirse-na-mean\\\/bunachar-sonrai-uineireacht-na-mean\\\/#breadcrumb\"},\"inLanguage\":\"ga-IE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/tionscal-gairmithe\\\/coid-reachtaiocht\\\/reachtaiocht\\\/an-gniomh-eorpach-um-shaoirse-na-mean\\\/bunachar-sonrai-uineireacht-na-mean\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/tionscal-gairmithe\\\/coid-reachtaiocht\\\/reachtaiocht\\\/an-gniomh-eorpach-um-shaoirse-na-mean\\\/bunachar-sonrai-uineireacht-na-mean\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tionscal &#038; gairmithe\",\"item\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/tionscal-gairmithe\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3id &#038; reachta\u00edocht\",\"item\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/tionscal-gairmithe\\\/coid-reachtaiocht\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Reachta\u00edocht\",\"item\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/tionscal-gairmithe\\\/coid-reachtaiocht\\\/reachtaiocht\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"An Gn\u00edomh Eorpach um Shaoirse na Me\u00e1n\",\"item\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/tionscal-gairmithe\\\/coid-reachtaiocht\\\/reachtaiocht\\\/an-gniomh-eorpach-um-shaoirse-na-mean\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Bunachar sonra\u00ed \u00fain\u00e9ireacht na me\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/#website\",\"url\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/\",\"name\":\"Coimisiun na Mean\",\"description\":\"Coimisi\u00fan na Me\u00e1n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ga-IE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/#organization\",\"name\":\"Coimisiun na Mean\",\"url\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ga-IE\",\"@id\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cnam.ie\\\/app\\\/uploads\\\/2024\\\/12\\\/Website-image-with-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cnam.ie\\\/app\\\/uploads\\\/2024\\\/12\\\/Website-image-with-logo.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Coimisiun na Mean\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cnam.ie\\\/ga\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNaM.Ireland\\\/\",\"https:\\\/\\\/x.com\\\/CNaM_ie\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bunachar sonra\u00ed \u00fain\u00e9ireacht na me\u00e1n - Coimisi\u00fan na Me\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/an-gniomh-eorpach-um-shaoirse-na-mean\/bunachar-sonrai-uineireacht-na-mean\/","og_locale":"ga_IE","og_type":"article","og_title":"Bunachar sonra\u00ed \u00fain\u00e9ireacht na me\u00e1n - Coimisi\u00fan na Me\u00e1n","og_description":"Is \u00e9 is aidhm d\u2019Airteagal 6 den Ghn\u00edomh Eorpach um Shaoirse na Me\u00e1n (GESM) tr\u00e9dhearcacht in \u00fain\u00e9ireacht na me\u00e1n a r\u00e1th\u00fa agus cuirtear d\u2019oibleag\u00e1id ar na Ballst\u00e1it leis \u00e9 a chur de ch\u00faram ar chomhlachta\u00ed inni\u00fala forbairt a dh\u00e9anamh ar bhunachair sonra\u00ed n\u00e1isi\u00fanta maidir le h\u00fain\u00e9ireacht na me\u00e1n. T\u00e1 dh\u00e1 bhunachar sonra\u00ed \u00fain\u00e9ireachta me\u00e1n \u00e1 [&hellip;]","og_url":"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/an-gniomh-eorpach-um-shaoirse-na-mean\/bunachar-sonrai-uineireacht-na-mean\/","og_site_name":"Coimisi\u00fan na Me\u00e1n","article_publisher":"https:\/\/www.facebook.com\/CNaM.Ireland\/","article_modified_time":"2025-11-11T15:47:48+00:00","twitter_card":"summary_large_image","twitter_site":"@CNaM_ie","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/an-gniomh-eorpach-um-shaoirse-na-mean\/bunachar-sonrai-uineireacht-na-mean\/","url":"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/an-gniomh-eorpach-um-shaoirse-na-mean\/bunachar-sonrai-uineireacht-na-mean\/","name":"Bunachar sonra\u00ed \u00fain\u00e9ireacht na me\u00e1n - Coimisi\u00fan na Me\u00e1n","isPartOf":{"@id":"https:\/\/www.cnam.ie\/ga\/#website"},"datePublished":"2025-09-19T14:25:56+00:00","dateModified":"2025-11-11T15:47:48+00:00","breadcrumb":{"@id":"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/an-gniomh-eorpach-um-shaoirse-na-mean\/bunachar-sonrai-uineireacht-na-mean\/#breadcrumb"},"inLanguage":"ga-IE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/an-gniomh-eorpach-um-shaoirse-na-mean\/bunachar-sonrai-uineireacht-na-mean\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/an-gniomh-eorpach-um-shaoirse-na-mean\/bunachar-sonrai-uineireacht-na-mean\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cnam.ie\/ga\/"},{"@type":"ListItem","position":2,"name":"Tionscal &#038; gairmithe","item":"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/"},{"@type":"ListItem","position":3,"name":"C\u00f3id &#038; reachta\u00edocht","item":"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/"},{"@type":"ListItem","position":4,"name":"Reachta\u00edocht","item":"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/"},{"@type":"ListItem","position":5,"name":"An Gn\u00edomh Eorpach um Shaoirse na Me\u00e1n","item":"https:\/\/www.cnam.ie\/ga\/tionscal-gairmithe\/coid-reachtaiocht\/reachtaiocht\/an-gniomh-eorpach-um-shaoirse-na-mean\/"},{"@type":"ListItem","position":6,"name":"Bunachar sonra\u00ed \u00fain\u00e9ireacht na me\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/www.cnam.ie\/ga\/#website","url":"https:\/\/www.cnam.ie\/ga\/","name":"Coimisiun na Mean","description":"Coimisi\u00fan na Me\u00e1n","publisher":{"@id":"https:\/\/www.cnam.ie\/ga\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cnam.ie\/ga\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ga-IE"},{"@type":"Organization","@id":"https:\/\/www.cnam.ie\/ga\/#organization","name":"Coimisiun na Mean","url":"https:\/\/www.cnam.ie\/ga\/","logo":{"@type":"ImageObject","inLanguage":"ga-IE","@id":"https:\/\/www.cnam.ie\/ga\/#\/schema\/logo\/image\/","url":"https:\/\/www.cnam.ie\/app\/uploads\/2024\/12\/Website-image-with-logo.jpg","contentUrl":"https:\/\/www.cnam.ie\/app\/uploads\/2024\/12\/Website-image-with-logo.jpg","width":1200,"height":800,"caption":"Coimisiun na Mean"},"image":{"@id":"https:\/\/www.cnam.ie\/ga\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNaM.Ireland\/","https:\/\/x.com\/CNaM_ie"]}]}},"spectra_custom_meta":{"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_last_translation_edit_mode":["native-editor"],"_wpml_word_count":["283"],"_edit_lock":["1762876073:12"],"_relevanssi_related_posts":["16335,7618,7630,15122,707,3328"],"_edit_last":["12"],"_wp_page_template":[""],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_yoast_wpseo_content_score":["60"],"_yoast_wpseo_estimated-reading-time-minutes":["2"],"_uag_page_assets":["a:9:{s:3:\"css\";s:70931:\".wp-block-uagb-container.uagb-block-1d5875b5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1d5875b5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1d5875b5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1d5875b5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1d5875b5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1d5875b5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1d5875b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 50px;}.wp-block-uagb-container.uagb-block-1d5875b5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 5px !important;margin-bottom: 20px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 50px;}.wp-block-uagb-container.uagb-block-2f005527 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2f005527 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2f005527 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2f005527 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2f005527 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2f005527{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2f005527 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2f005527{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-d9b72e84.wp-block-uagb-advanced-heading .uagb-heading-text{color: #3a1300;}.wp-block-uagb-advanced-heading.uagb-block-d9b72e84.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d9b72e84.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d9b72e84.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d9b72e84.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d9b72e84 .uagb-heading-text{font-size: 22px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-1d5875b5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1d5875b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-1d5875b5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 5px !important;margin-bottom: 20px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2f005527{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2f005527 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2f005527{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-1d5875b5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1d5875b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1d5875b5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 5px !important;margin-bottom: 20px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2f005527{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2f005527 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2f005527{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}.wp-block-uagb-container.uagb-block-be51d9cd .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-be51d9cd .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-be51d9cd .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-be51d9cd .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-be51d9cd .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-be51d9cd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-be51d9cd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-be51d9cd{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e336568b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e336568b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e336568b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e336568b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e336568b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e336568b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-e336568b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 0px;max-width: 100% !important;}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 3px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3b49152a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 3px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-ccfe5d54{min-height: 2px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: #dcbcaa;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-10e3b54c.uagb-loop-container{flex-direction: column;gap: 1px;}.uagb-block-10e3b54c.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-block-f4a2286e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f4a2286e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f4a2286e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f4a2286e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f4a2286e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f4a2286e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-f4a2286e{box-shadow: 0px 0px   #00000070 ;padding-top: 1em;padding-bottom: 1em;padding-left: 1em;padding-right: 1em;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #f8f1ee;;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ce2b1e;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b.wp-block-uagb-advanced-heading {margin-bottom: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b .uagb-heading-text{font-size: 14px;}.wp-block-uagb-advanced-heading.uagb-block-e2186ba7.wp-block-uagb-advanced-heading {padding-top: 6px;padding-right: 0px;padding-bottom: 12px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e2186ba7.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-e2186ba7.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e2186ba7.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e2186ba7.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e2186ba7.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-7fb3b530 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fb3b530 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fb3b530 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fb3b530 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fb3b530 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fb3b530{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-7fb3b530{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 0px;max-width: 100% !important;}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 3px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3b49152a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 3px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-ccfe5d54{min-height: 2px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: #dcbcaa;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-24096991 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-24096991 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-24096991 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-24096991 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-24096991 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-24096991{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-24096991{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;max-width: 100% !important;}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 3px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3b49152a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 3px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-ccfe5d54{min-height: 2px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: #dcbcaa;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-10e3b54c.uagb-loop-container{flex-direction: column;gap: 24px;}.uagb-block-10e3b54c.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-block-f4a2286e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f4a2286e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f4a2286e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f4a2286e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f4a2286e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f4a2286e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-f4a2286e{box-shadow: 0px 0px   #00000070 ;padding-top: 1em;padding-bottom: 1em;padding-left: 1em;padding-right: 1em;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #f8f1ee;;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ce2b1e;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b.wp-block-uagb-advanced-heading {margin-bottom: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6183ee4b .uagb-heading-text{font-size: 14px;}.wp-block-uagb-advanced-heading.uagb-block-e2186ba7.wp-block-uagb-advanced-heading {padding-top: 6px;padding-right: 0px;padding-bottom: 12px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e2186ba7.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-e2186ba7.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e2186ba7.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e2186ba7.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e2186ba7.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-59adacea .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-59adacea .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-59adacea .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-59adacea .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-59adacea .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-59adacea{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-59adacea{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;max-width: 100% !important;}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 3px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3b49152a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 3px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-ccfe5d54{min-height: 2px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: #dcbcaa;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-59adacea .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-59adacea .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-59adacea .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-59adacea .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-59adacea .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-59adacea{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-59adacea{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;max-width: 100% !important;}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b49152a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 3px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3b49152a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 3px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4440813.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ccfe5d54 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1320px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-ccfe5d54{min-height: 2px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: #dcbcaa;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-90ffb99d.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {flex-direction: column;gap: 10px;}.uagb-block-90ffb99d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: flex-start;}.uagb-block-90ffb99d .uagb-button__wrapper{margin-top: 0em;margin-bottom: 0em;margin-left: 0em;margin-right: 0em;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;color: #ffffff;margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-2d61f266.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-2d61f266.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;color: #ffffff;margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-2d61f266.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-2d61f266.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;color: #ffffff;margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-958aa259.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;color: #ffffff;margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-958aa259.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-be51d9cd{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-be51d9cd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-be51d9cd{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e336568b{width: 100%;}.wp-block-uagb-container.uagb-block-e336568b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3b49152a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ccfe5d54{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #dcbcaa;;}.uagb-block-10e3b54c.uagb-loop-container{flex-direction: row;gap: 24px;}.uagb-block-10e3b54c.uagb-loop-container > .uagb-loop-post{width: calc( calc(100% - 1 * 24px ) \/ 2 );}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f4a2286e{width: 100%;}.wp-block-uagb-container.uagb-block-f4a2286e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f8f1ee;;align-items: flex-start;justify-content: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fb3b530{width: 100%;}.wp-block-uagb-container.uagb-block-7fb3b530{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3b49152a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ccfe5d54{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #dcbcaa;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-24096991{width: 100%;}.wp-block-uagb-container.uagb-block-24096991{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3b49152a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ccfe5d54{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #dcbcaa;;}.uagb-block-10e3b54c.uagb-loop-container{flex-direction: row;gap: 24px;}.uagb-block-10e3b54c.uagb-loop-container > .uagb-loop-post{width: calc( calc(100% - 1 * 24px ) \/ 2 );}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f4a2286e{width: 100%;}.wp-block-uagb-container.uagb-block-f4a2286e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f8f1ee;;align-items: flex-start;justify-content: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-59adacea{width: 100%;}.wp-block-uagb-container.uagb-block-59adacea{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3b49152a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ccfe5d54{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #dcbcaa;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-59adacea{width: 100%;}.wp-block-uagb-container.uagb-block-59adacea{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3b49152a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ccfe5d54{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #dcbcaa;;}.uagb-block-90ffb99d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: flex-start;}.uagb-block-90ffb99d.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-2d61f266.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-2d61f266.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-be51d9cd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-be51d9cd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-be51d9cd{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e336568b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-e336568b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3b49152a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ccfe5d54{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #dcbcaa;;flex-wrap: wrap;}.uagb-block-10e3b54c.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-10e3b54c.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f4a2286e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-f4a2286e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f8f1ee;;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fb3b530{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-7fb3b530{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3b49152a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ccfe5d54{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #dcbcaa;;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-24096991{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-24096991{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3b49152a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ccfe5d54{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #dcbcaa;;flex-wrap: wrap;}.uagb-block-10e3b54c.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-10e3b54c.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f4a2286e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-f4a2286e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f8f1ee;;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-59adacea{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-59adacea{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3b49152a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ccfe5d54{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #dcbcaa;;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-59adacea{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-59adacea{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b49152a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b49152a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3b49152a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ccfe5d54{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ccfe5d54 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ccfe5d54{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #dcbcaa;;flex-wrap: wrap;}.uagb-block-90ffb99d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: flex-start;}.uagb-block-90ffb99d.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-2d61f266.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-2d61f266.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-2d61f266 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-958aa259 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}\";s:2:\"js\";s:458:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-2d61f266' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-2d61f266' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-958aa259' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-958aa259' );\n});\n });\";s:18:\"current_block_list\";a:11:{i:0;s:14:\"uagb\/container\";i:2;s:21:\"uagb\/advanced-heading\";i:3;s:14:\"core\/paragraph\";i:4;s:9:\"core\/list\";i:5;s:14:\"core\/list-item\";i:6;s:12:\"core\/heading\";i:7;s:17:\"uagb\/loop-builder\";i:8;s:17:\"uagb\/loop-wrapper\";i:9;s:15:\"core\/categories\";i:10;s:12:\"uagb\/buttons\";i:11;s:18:\"uagb\/buttons-child\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778683054\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Padraig Foran","author_link":"https:\/\/www.cnam.ie\/ga\/author\/padraigf\/"},"uagb_comment_info":0,"uagb_excerpt":"Is \u00e9 is aidhm d\u2019Airteagal 6 den Ghn\u00edomh Eorpach um Shaoirse na Me\u00e1n (GESM) tr\u00e9dhearcacht in \u00fain\u00e9ireacht na me\u00e1n a r\u00e1th\u00fa agus cuirtear d\u2019oibleag\u00e1id ar na Ballst\u00e1it leis \u00e9 a chur de ch\u00faram ar chomhlachta\u00ed inni\u00fala forbairt a dh\u00e9anamh ar bhunachair sonra\u00ed n\u00e1isi\u00fanta maidir le h\u00fain\u00e9ireacht na me\u00e1n. T\u00e1 dh\u00e1 bhunachar sonra\u00ed \u00fain\u00e9ireachta me\u00e1n \u00e1&hellip;","_links":{"self":[{"href":"https:\/\/www.cnam.ie\/ga\/wp-json\/wp\/v2\/pages\/17956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cnam.ie\/ga\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cnam.ie\/ga\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cnam.ie\/ga\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cnam.ie\/ga\/wp-json\/wp\/v2\/comments?post=17956"}],"version-history":[{"count":3,"href":"https:\/\/www.cnam.ie\/ga\/wp-json\/wp\/v2\/pages\/17956\/revisions"}],"predecessor-version":[{"id":19109,"href":"https:\/\/www.cnam.ie\/ga\/wp-json\/wp\/v2\/pages\/17956\/revisions\/19109"}],"up":[{"embeddable":true,"href":"https:\/\/www.cnam.ie\/ga\/wp-json\/wp\/v2\/pages\/17934"}],"wp:attachment":[{"href":"https:\/\/www.cnam.ie\/ga\/wp-json\/wp\/v2\/media?parent=17956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}